{"id":2876970,"date":"2017-05-26T11:38:18","date_gmt":"2017-05-26T18:38:18","guid":{"rendered":"http:\/\/agpnoticias.com\/news\/?p=2876970"},"modified":"2017-12-12T11:29:11","modified_gmt":"2017-12-12T19:29:11","slug":"zinnia-garayzar-ve-crecer-su-proyecto-de-atletismo-en-cetys-ensenada","status":"publish","type":"post","link":"https:\/\/agpnoticias.com\/news\/zinnia-garayzar-ve-crecer-su-proyecto-de-atletismo-en-cetys-ensenada\/","title":{"rendered":"Zinnia Garayzar ve crecer su proyecto de atletismo en CETYS Ensenada"},"content":{"rendered":"<p>Ensenada, Baja California.- Desde que Zinnia Garayzar asumi\u00f3 la direcci\u00f3n del \u00e1rea de atletismo en CETYS Ensenada, a principios de la d\u00e9cada pasada, ha visto pasar por ah\u00ed a deportistas sobresalientes en competencias de car\u00e1cter nacional.<\/p>\n<p>De primera, recuerda a Guillermo y C\u00e9sar Collins, Ivanna Chapluk, Joanna Saad, Mar\u00eda Luis Mendoza y Mikhail Rudametkin, entre otros talentos que ha dirigido durante 16 a\u00f1os.<\/p>\n<p>La entrenadora nacida en Ensenada ha alternado con \u00e9xito esa experiencia con sus cargos como titular del Club Halcones y encargada de atletismo en la regi\u00f3n tanto por el Instituto del Deporte de Baja California (INDE) y la Comisi\u00f3n Nacional del Deporte (Conade).<\/p>\n<p>En la actualidad, el equipo de atletismo de CETYS cuenta con las potenciales medallistas de Olimpiada Nacional, Yassiel Ledesma y Jocelyn Barrera, como parte de un grupo \u201ccon mucho talento\u201d.<\/p>\n<p><a href=\"http:\/\/agpnoticias.com\/news\/zinnia-garayzar-ve-crecer-su-proyecto-de-atletismo-en-cetys-ensenada\/img_6370\/\" rel=\"attachment wp-att-2876974\"><img fetchpriority=\"high\" decoding=\"async\" class=\"aligncenter size-full wp-image-2876974\" src=\"http:\/\/agpnoticias.com\/news\/wp-content\/uploads\/2017\/05\/IMG_6370-e1495749022359.jpg\" alt=\"\" width=\"600\" height=\"371\" \/><\/a><\/p>\n<p>\u201cInici\u00e9 en el atletismo a los ocho a\u00f1os, as\u00ed que he sido atleta de alto rendimiento y luego entrenadora casi toda mi vida\u201d, refiri\u00f3.<\/p>\n<p>En t\u00e9rminos acad\u00e9micos, \u201cestudi\u00e9 la Licenciatura de Educaci\u00f3n F\u00edsica especializada y certificada en atletismo\u201d.<\/p>\n<p>\u201cEmpec\u00e9 en Colegio M\u00e9xico como entrenadora ya hace 18 a\u00f1os y permanec\u00ed 10 a\u00f1os ah\u00ed en atletismo, para m\u00e1s tarde ser maestra educaci\u00f3n f\u00edsica en secundaria y m\u00e1s adelante coordinadora.<\/p>\n<p>\u201cTermin\u00e9 esa experiencia cuando se me abri\u00f3 la oportunidad en el Centro de Alto Rendimiento de Ensenada por una invitaci\u00f3n del director del INDE, Sa\u00fal Castro, ya hace seis a\u00f1os. Y este a\u00f1o ya fui contratada por Conade gracias a los resultados\u201d, refiri\u00f3.<\/p>\n<p>&nbsp;<\/p>\n<p>Adem\u00e1s de dirigir al grupo de atletas convencionales, Zinnia Garayzar tiene a su cargo el trabajo con los deportistas ciegos y d\u00e9biles visuales, con Jocelyn Barrera destacando en ambas modalidades.<\/p>\n<p>\u201cElla, que es una estudiante muy destacada y dedicada de CETYS, participa como d\u00e9bil visual y convencional. En la eliminatoria de Conadems tuvo un excelente desempe\u00f1o en garrocha\u201d, agreg\u00f3.<\/p>\n<p>Como titular del \u00e1rea de ciegos y d\u00e9biles visuales, precis\u00f3 que \u201cen la Paralimpiada pasada participaron con 15 atletas de Ensenada y llegaron 23 medallas\u201d.<\/p>\n<p><a href=\"http:\/\/agpnoticias.com\/news\/zinnia-garayzar-ve-crecer-su-proyecto-de-atletismo-en-cetys-ensenada\/img_6383\/\" rel=\"attachment wp-att-2876975\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-2876975\" src=\"http:\/\/agpnoticias.com\/news\/wp-content\/uploads\/2017\/05\/IMG_6383-e1495748980274.jpg\" alt=\"\" width=\"389\" height=\"472\" \/><\/a><\/p>\n<p>En cuanto al proyecto de Halcones, uno de los equipos m\u00e1s productivos de Baja California, record\u00f3 que \u201cnaci\u00f3 cuando a\u00fan estudiaba la universidad con ni\u00f1os del Colegio M\u00e9xico que ten\u00edan cualidades y despu\u00e9s se fueron sumando ni\u00f1os de otras escuelas\u201d.<\/p>\n<p>\u201cEntonces eran 10 integrantes y ahora tenemos 158, todos atendidos por maestros titulados y recibidos\u201d, puntualiz\u00f3.<\/p>\n<p>Del proyecto de becas de CETYS dijo que una de sus tareas es reclutar talentos que \u201ccarezcan de recursos para que puedan sumarse a la instituci\u00f3n\u201d.<\/p>\n<p>En ese sentido, destac\u00f3 el caso de Christopher Agui\u00f1aga, \u201cun atleta de excelentes resultados como estudiante de prepa y universidad, ya graduado\u201d.<\/p>\n<p>\u201cEmpezamos con un equipo representativo y ahora buscamos atletas de calidad que est\u00e9n entre los mejores del pa\u00eds\u201d, apunt\u00f3.<\/p>\n<p>La entrenadora invit\u00f3 a los atletas locales, en edades de preparatoria y universidad, \u201ca que se acerquen a CETYS porque existen muchas posibilidades de tener la mejor preparaci\u00f3n acad\u00e9mica y completarla con el impulso que se le est\u00e1 dando al deporte\u201d.<\/p>\n<p><a href=\"http:\/\/agpnoticias.com\/news\/zinnia-garayzar-ve-crecer-su-proyecto-de-atletismo-en-cetys-ensenada\/img_6323\/\" rel=\"attachment wp-att-2876973\"><img decoding=\"async\" class=\"aligncenter size-full wp-image-2876973\" src=\"http:\/\/agpnoticias.com\/news\/wp-content\/uploads\/2017\/05\/IMG_6323-e1495749057162.jpg\" alt=\"\" width=\"800\" height=\"533\" \/><\/a><\/p>\n<p>&nbsp;<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ensenada, Baja California.- Desde que Zinnia Garayzar asumi\u00f3 la direcci\u00f3n del \u00e1rea de atletismo en&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2876976,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[31,879,704,7],"tags":[595],"class_list":["post-2876970","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-atletismo","category-cetys-universidad","category-deporte-estudiantil","category-deportes","tag-destacado"],"_links":{"self":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2876970","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/comments?post=2876970"}],"version-history":[{"count":5,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2876970\/revisions"}],"predecessor-version":[{"id":2877010,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2876970\/revisions\/2877010"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media\/2876976"}],"wp:attachment":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media?parent=2876970"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/categories?post=2876970"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/tags?post=2876970"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}