{"id":2891764,"date":"2018-07-16T01:14:33","date_gmt":"2018-07-16T08:14:33","guid":{"rendered":"http:\/\/agpnoticias.com\/news\/?p=2891764"},"modified":"2018-07-17T18:29:21","modified_gmt":"2018-07-18T01:29:21","slug":"seleccion-nacional-mexicana-visita-gimnasio-auditorio-de-cetys-ensenada","status":"publish","type":"post","link":"https:\/\/agpnoticias.com\/news\/seleccion-nacional-mexicana-visita-gimnasio-auditorio-de-cetys-ensenada\/","title":{"rendered":"Selecci\u00f3n Nacional Mexicana visita gimnasio-auditorio de CETYS Ensenada"},"content":{"rendered":"<p>Ensenada, Baja California.- El gimnasio-auditorio CETYS Campus Internacional Ensenada sirvi\u00f3 para la despedida de la selecci\u00f3n mexicana femenil de basquetbol que participar\u00e1 en los Primeros Juegos Panamericanos Universitarios FISU Am\u00e9rica, programados en Sao Paulo, Brasil, del 19 al 29 julio.<\/p>\n<p>El seleccionado dirigido por el entrenador del Sistema CETYS, C\u00e9sar Valencia, enfrent\u00f3 al selectivo varonil de Preparatoria Ensenada despu\u00e9s de tres semanas de concentraci\u00f3n en el Centro de Alto Rendimiento de Tijuana.<\/p>\n<p>\u201cAl haber ganado el evento del CONDDE (Consejo Nacional del Deporte de la Educaci\u00f3n) nos invitaron a dirigir a la selecci\u00f3n y convocamos a las mejores jugadoras de M\u00e9xico y algunas que estudian en el extranjero\u201d, indic\u00f3 el t\u00e9cnico.<\/p>\n<p>Sobre la expectativa en la competencia que celebrar\u00e1 su primera edici\u00f3n, dijo que \u201cla aspiraci\u00f3n es traer una medalla, representando lo mejor posible al pa\u00eds haciendo un buen papel para tratar de ir a la Universiada Mundial de Mil\u00e1n el pr\u00f3ximo a\u00f1o\u201d.<\/p>\n<p>\u201cHay jugadoras de las mejores universidades de M\u00e9xico y cuatro que estudian en los Estados Unidos, aunque faltaron algunas que van a Barranquilla con la selecci\u00f3n de M\u00e9xico a los Juegos Centroamericanos y del Caribe\u201d, precis\u00f3.<\/p>\n<p>C\u00e9sar Valencia coron\u00f3 uno de sus mejores periodos como entrenador del Sistema CETYS, ya con alrededor de 20 a\u00f1os de militancia en la instituci\u00f3n, al ganar en Tijuana el campeonato de Los Ocho Grandes de la Liga ABE, as\u00ed como el t\u00edtulo de Universiada Nacional (CONDDE).<\/p>\n<p>\u201cHa sido un a\u00f1o muy exitoso ganando esos dos eventos que eran el objetivo de muchos a\u00f1os no s\u00f3lo de nosotros sino de todos los entrenador de Baja California, y sobre todo porque lo hicimos casi con el cien por ciento de jugadoras del estado\u201d, refiri\u00f3.<\/p>\n<figure id=\"attachment_2891766\" aria-describedby=\"caption-attachment-2891766\" style=\"width: 700px\" class=\"wp-caption aligncenter\"><img fetchpriority=\"high\" decoding=\"async\" class=\"size-full wp-image-2891766\" src=\"http:\/\/agpnoticias.com\/news\/wp-content\/uploads\/2018\/07\/IMG_3708-e1531728759736.jpg\" alt=\"\" width=\"700\" height=\"467\" \/><figcaption id=\"caption-attachment-2891766\" class=\"wp-caption-text\">Alejandro Ortiz dio la bienvenida a C\u00e9sar Valencia y Viridiana Villavicencio<\/figcaption><\/figure>\n<p>En cuanto al gimnasio-auditorio de CETYS Ensenada elogi\u00f3 \u201cla instalaci\u00f3n de calidad con el gran trabajo que hace (el coordinador deportivo) Alejandro Ortiz en una ciudad con tanto talento de basquetbol\u201d.<\/p>\n<p>\u201cMe ha tocado trabajar con grandes jugadores de Ensenada como Claudia Careaga, Jos\u00e9 Luis Bucio, Ra\u00fal B\u00f3rquez, Cynthia Kanemoto y \u00a0Viridiana Villavicencio, quien ahora me acompa\u00f1a en el cuerpo t\u00e9cnico de esta selecci\u00f3n\u201d, concluy\u00f3.<\/p>\n<p>Alejandro Ortiz dio la bienvenida a la selecci\u00f3n femenil, por primera vez en el gimnasio-auditorio, y expres\u00f3 su deseo de que el equipo varonil de Preparatoria, el cual est\u00e1 a su cargo, haya servido para la preparaci\u00f3n de la selecci\u00f3n mexicana femenil.<\/p>\n<p>\u201cEs otro evento m\u00e1s de importancia que recibimos aqu\u00ed en esta instalaci\u00f3n donde nos da orgullo contar con esta selecci\u00f3n que va a los primeros Juegos Panamericanos que ser\u00e1n en Brasil. A C\u00e9sar lo conozco de muchos a\u00f1os y s\u00e9 de su calidad, igual que Viri Villavicencio, que en su momento fue mi jugadora\u201d, agreg\u00f3.<\/p>\n<p>La selecci\u00f3n viajar\u00e1 el viernes a Brasil luego de pasar por la Comisi\u00f3n Nacional del Deporte en la Ciudad de M\u00e9xico.<\/p>\n<p><img decoding=\"async\" class=\"aligncenter size-full wp-image-2891767\" src=\"http:\/\/agpnoticias.com\/news\/wp-content\/uploads\/2018\/07\/IMG_3759-e1531728791370.jpg\" alt=\"\" width=\"800\" height=\"595\" \/><\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ensenada, Baja California.- El gimnasio-auditorio CETYS Campus Internacional Ensenada sirvi\u00f3 para la despedida de la&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2891765,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[35,879,704,7],"tags":[888,691],"class_list":["post-2891764","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-basquetbol","category-cetys-universidad","category-deporte-estudiantil","category-deportes","tag-destacado2","tag-especiales"],"_links":{"self":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2891764","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/comments?post=2891764"}],"version-history":[{"count":4,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2891764\/revisions"}],"predecessor-version":[{"id":2891769,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2891764\/revisions\/2891769"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media\/2891765"}],"wp:attachment":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media?parent=2891764"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/categories?post=2891764"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/tags?post=2891764"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}