{"id":2897927,"date":"2018-11-09T10:38:01","date_gmt":"2018-11-09T18:38:01","guid":{"rendered":"http:\/\/agpnoticias.com\/news\/?p=2897927"},"modified":"2018-11-09T12:39:20","modified_gmt":"2018-11-09T20:39:20","slug":"zorros-del-cetys-ensenada-rumbo-a-mexicali-por-el-pase-a-semifinales","status":"publish","type":"post","link":"https:\/\/agpnoticias.com\/news\/zorros-del-cetys-ensenada-rumbo-a-mexicali-por-el-pase-a-semifinales\/","title":{"rendered":"Zorros del CETYS Ensenada rumbo a Mexicali por el pase a semifinales"},"content":{"rendered":"<p>Ensenada, Baja California.- No ganaron pero fue el mejor juego de los Zorros del CETYS Ensenada. Ante los l\u00edderes Zorros del CETYS Mexicali, tres semanas atr\u00e1s, apenas perdieron por 12-7.<\/p>\n<p>Hoy, con los pron\u00f3sticos en contra pero el aprendizaje de aquella derrota, el equipo del campus ensenadense, dirigido por Juan Carlos Garc\u00eda, buscar\u00e1 el pase a la semifinal contra el mismo rival.<\/p>\n<p>\u201cEstuvo muy cerrado el juego de temporada regular y hemos estado trabajando en los errores cometidos ese d\u00eda\u201d, indic\u00f3 el entrenador en jefe de los Zorros de Ensenada, sextos tras la conclusi\u00f3n de la temporada regular de la Organizaci\u00f3n Estudiantil de Futbol Americano (OEFA).<\/p>\n<p>En cuanto a aquel juego, consider\u00f3 que el juego fue term\u00f3metro para evaluar la evoluci\u00f3n de una temporada a otra pues quedaron atr\u00e1s las diferencias abultadas.<\/p>\n<p>La clave de la derrota fueron varios balones perdidos, mientras que la virtud frente al l\u00edder CETYS Mexicali fue detener su ataque terrestre.<\/p>\n<p>El juego de la categor\u00eda varsity, Divisi\u00f3n 1, iniciar\u00e1 este d\u00eda a las 19:00 horas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ensenada, Baja California.- No ganaron pero fue el mejor juego de los Zorros del CETYS&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2897929,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[7,33],"tags":[595],"class_list":["post-2897927","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-deportes","category-futbol-americano","tag-destacado"],"_links":{"self":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2897927","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/comments?post=2897927"}],"version-history":[{"count":2,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2897927\/revisions"}],"predecessor-version":[{"id":2897930,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2897927\/revisions\/2897930"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media\/2897929"}],"wp:attachment":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media?parent=2897927"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/categories?post=2897927"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/tags?post=2897927"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}