{"id":2900623,"date":"2018-12-26T17:49:42","date_gmt":"2018-12-27T01:49:42","guid":{"rendered":"http:\/\/agpnoticias.com\/news\/?p=2900623"},"modified":"2018-12-27T21:11:45","modified_gmt":"2018-12-28T05:11:45","slug":"futbol-americano-zorros-evolucion-y-protagonismo","status":"publish","type":"post","link":"https:\/\/agpnoticias.com\/news\/futbol-americano-zorros-evolucion-y-protagonismo\/","title":{"rendered":"Futbol Americano: Zorros, evoluci\u00f3n y protagonismo"},"content":{"rendered":"\n<p class=\"wp-block-paragraph\">Ensenada, Baja California.- Los Zorros del CETYS cumplieron con una de sus metas de 2018: se convirtieron en protagonistas de uno de los mejores juegos de playoffs en la categor\u00eda Varsity de la Organizaci\u00f3n Estudiantil de Futbol Americano (OEFA).<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">Lo perdieron en Mexicali contra los locales Zorros, sin embargo, en opini\u00f3n de Juan Carlos Garc\u00eda Morales, \u00abese juego quedar\u00e1 en la memoria de los jugadores que siguen en el equipo porque se dieron cuenta de que s\u00ed pueden\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abSe la creyeron\u00bb, dijo el entrenador en jefe.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">A\u00fan cuando los Zorros ganaron la Segunda Divisi\u00f3n en a\u00f1os consecutivos, el hecho de llegar a playoffs de la m\u00e1xima categor\u00eda durante la m\u00e1s reciente temporada \u00abes un gran avance\u00bb.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abHicimos cosas diferentes desde el tryout para reclutar al mejor talento y luego realizar un trabajo especial con los j\u00f3venes desde el aspecto f\u00edsico, d\u00e1ndoles el seguimiento adecuado. <\/p>\n\n\n\n<p class=\"wp-block-paragraph\">\u00abTambi\u00e9n involucramos a los pap\u00e1s para tener un mayor compromiso de los jugadores y eso fue clave para enfocarnos\u00bb, agreg\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">En cuanto a la caracter\u00edstica principal del grupo a su cargo, consider\u00f3: \u00abFue un plantel aguerrido\u00bb.<br> \u00abSeleccionamos al mejor talento de Ensenada, justo lo que necesit\u00e1bamos tanto de CETYS como los extranjeros (elementos de otras escuelas)\u00bb, apunt\u00f3.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De un a\u00f1o a otro, evalu\u00f3, \u00abla evoluci\u00f3n fue notoria al enfrentarnos a los mejores equipos del estado con varios juegos parejos y algunos se decidieron solo porque tenemos un grupo reducido de jugadores que la mayor\u00eda de los equipos\u00bb. <br> \u00abAnd\u00e1bamos en 27 o 28 jugadores cuando los dem\u00e1s andaban en 45, as\u00ed que ese fue un factor\u00bb, precis\u00f3.<br><\/p>\n\n\n\n<p class=\"wp-block-paragraph\">De cara al pr\u00f3ximo a\u00f1o, el head coach de los Zorros planea una renovaci\u00f3n pues solo permanecer\u00e1n 10 integrantes de la plantilla.<br> \u00abYa trabajamos en el reclutamiento para que el equipo siga competitivo como este a\u00f1o en el que demostramos que se puede trascender. Avanzaremos y cada paso ser\u00e1 con pies de plomo, bien firme\u00bb, afirm\u00f3.<\/p>\n\n\n\n<figure class=\"wp-block-image\"><img fetchpriority=\"high\" decoding=\"async\" width=\"600\" height=\"404\" src=\"http:\/\/agpnoticias.com\/news\/wp-content\/uploads\/2018\/12\/IMG_6451-e1545875303745.jpg\" alt=\"\" class=\"wp-image-2900625\"\/><\/figure>\n\n\n\n<p class=\"wp-block-paragraph\"><b>Gael Isaac Su\u00e1rez Alvarado <\/b><br> Fecha de nacimiento: 15 febrero 2002 <br> Grado escolar: Tercer semestre de Preparatoria<br> Posici\u00f3n: Corredor <br> N\u00famero: 18<br> Resumen 2018 y expectativas 2019: Tanto lo bueno como lo malo nos sirvi\u00f3, sobre todo a nosotros, los de primer a\u00f1o. Fue un mayor compromiso el que tom\u00f3 todo el grupo para mantenernos en Primera Divisi\u00f3n y llegar a playoffs. Muchos de los veteranos ya se van y nosotros tendremos que demostrar la experiencia adquirida esta temporada.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Luis Gabriel Silva Romero<\/strong><br> 23 de abril de 2001<br> Grado escolar: Quinto semestre de Preparatoria<br> Posici\u00f3n: Ala defensiva<br> N\u00famero: 79<br> Resumen 2018 y expectativas 2019: Fue un a\u00f1o muy fuerte con una evoluci\u00f3n que se not\u00f3 al llegar a los playoffs de Primera Divisi\u00f3n. Individualmente siento que di lo mejor que tuve para ayudar al equipo, como creo que lo hicieron todos mis compa\u00f1eros. Cuando llegu\u00e9 me sent\u00ed cobijado por los que entonces eran veteranos y ahora tuve la oportunidad de ayudar a los novatos que llegaron. Cumpl\u00ed mi tercer a\u00f1o con Zorros y me retiro del equipo, pero creo que se queda una muy buena base.<\/p>\n\n\n\n<p class=\"wp-block-paragraph\"><strong>Guillermo Galv\u00e1n Rub\u00ed<\/strong><br> Fecha de nacimiento: 10 de agosto de 2002<br> Grado escolar: Tercer semestre de Preparatoria<br> Posici\u00f3n: Linebacker<br> N\u00famero: 55<br> Resumen 2018 y expectativas 2019: Lo m\u00e1s importante fue mantenernos en Primera Divisi\u00f3n con el apoyo de los coaches que siempre apoyaron al grupo de jugadores, bien unidos para no bajar a Segunda. En lo personal trat\u00e9 de mejorar como linebacker y trabajar m\u00e1s en el gimnasio. Avanzamos bastante este a\u00f1o porque logramos ser competitivos contra equipos fuertes a los que les dimos buenas batallas.<\/p>\n","protected":false},"excerpt":{"rendered":"<p>Ensenada, Baja California.- Los Zorros del CETYS cumplieron con una de sus metas de 2018:&#8230;<\/p>\n","protected":false},"author":1,"featured_media":2900626,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[879,704,7,33],"tags":[888,878],"class_list":["post-2900623","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cetys-universidad","category-deporte-estudiantil","category-deportes","category-futbol-americano","tag-destacado2","tag-tendencias"],"_links":{"self":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2900623","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/comments?post=2900623"}],"version-history":[{"count":2,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2900623\/revisions"}],"predecessor-version":[{"id":2900627,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2900623\/revisions\/2900627"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media\/2900626"}],"wp:attachment":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media?parent=2900623"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/categories?post=2900623"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/tags?post=2900623"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}