{"id":2913026,"date":"2020-02-15T15:19:14","date_gmt":"2020-02-15T23:19:14","guid":{"rendered":"https:\/\/agpnoticias.com\/news\/?p=2913026"},"modified":"2020-02-16T16:41:30","modified_gmt":"2020-02-17T00:41:30","slug":"cetys-continua-con-convocatoria-a-deportistas-aspirantes-a-beca","status":"publish","type":"post","link":"https:\/\/agpnoticias.com\/news\/cetys-continua-con-convocatoria-a-deportistas-aspirantes-a-beca\/","title":{"rendered":"CETYS contin\u00faa con convocatoria a deportistas aspirantes a beca"},"content":{"rendered":"\n<p>Ensenada, Baja California.- Con la evaluaci\u00f3n a talentos en futbol americano, CETYS Universidad Campus Internacional Ensenada culmin\u00f3 la primera de las etapas de tryouts para abastecer a sus representativos con deportistas aspirantes a beca.<\/p>\n<p>Alejandro Ortiz Soto inform\u00f3 que son cerca del centenar de estudiantes de secundaria que han sido observados tanto en futbol americano como en voleibol, baloncesto (ambas ramas), flag futbol, atletismo, futbol y beisbol.<\/p>\n<p>\u201cEsto no acaba aqu\u00ed, continuaremos con los tryouts para los Zorros de CETYS Preparatoria y los haremos cada mes. Promoci\u00f3n y deportes buscamos al talento acad\u00e9mico y deportivo\u201d, refiri\u00f3 el coordinador deportivo de CETYS.<\/p>\n<p>\u201cLo que sigue es continuar los tryouts en aspectos f\u00edsicos y t\u00e9cnicos, fundamentos, con el requisito de obtener 49 puntos en el examen de admisi\u00f3n para despu\u00e9s hacerles el ofrecimiento de beca deportiva\u201d, explic\u00f3.<\/p>\n<p>E invit\u00f3 a los interesados a acudir a la coordinaci\u00f3n de deportes de CETYS, cuya oficina est\u00e1 ubicada en el Gimnasio Auditorio Quimical. \u201cLas puertas est\u00e1n abiertas, ac\u00e9rquense a pedir informes\u201d, concluy\u00f3.<\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2913029,"comment_status":"open","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[879,704],"tags":[888],"class_list":["post-2913026","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-cetys-universidad","category-deporte-estudiantil","tag-destacado2"],"_links":{"self":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2913026","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/comments?post=2913026"}],"version-history":[{"count":1,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2913026\/revisions"}],"predecessor-version":[{"id":2913027,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2913026\/revisions\/2913027"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media\/2913029"}],"wp:attachment":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media?parent=2913026"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/categories?post=2913026"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/tags?post=2913026"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}