{"id":2964633,"date":"2023-11-14T15:38:36","date_gmt":"2023-11-14T23:38:36","guid":{"rendered":"https:\/\/agpnoticias.com\/news\/?p=2964633"},"modified":"2023-11-14T15:40:19","modified_gmt":"2023-11-14T23:40:19","slug":"schumaker-manager-del-ano-en-la-nacional-por-su-trabajo-con-miami","status":"publish","type":"post","link":"https:\/\/agpnoticias.com\/news\/schumaker-manager-del-ano-en-la-nacional-por-su-trabajo-con-miami\/","title":{"rendered":"Schumaker, manager del a\u00f1o en la Nacional por su trabajo con Miami"},"content":{"rendered":"\n\n\n<p>Miami, Florida.- En su primera temporada al frente, Skip Schumaker llev\u00f3 a los Marlins a la cuarta postemporada en la historia de la franquicia, y la primera en una campa\u00f1a no acortada desde 2003.<\/p>\n<p>Mientras Miami fue superado por 57 carreras, Schumaker gui\u00f3 al club a un incre\u00edble r\u00e9cord de 33-14 en juegos de una carrera, lo que marc\u00f3 la diferencia en una carrera muy estrecha por el comod\u00edn de la Liga Nacional.<\/p>\n<p>Schumaker, un ex jugador utilitario que pas\u00f3 11 a\u00f1os en las Mayores, es el cuarto capit\u00e1n de los Marlins en ganar el honor de Manager del A\u00f1o de la Liga Nacional, uni\u00e9ndose a Jack McKeon (2003), Joe Girardi (2006) y Don Mattingly (2020).<\/p>\n<p><em>Informaci\u00f3n: MLB.<\/em><\/p>\n","protected":false},"excerpt":{"rendered":"","protected":false},"author":1,"featured_media":2964634,"comment_status":"closed","ping_status":"closed","sticky":false,"template":"","format":"standard","meta":{"footnotes":""},"categories":[30,1142,1151],"tags":[907],"class_list":["post-2964633","post","type-post","status-publish","format-standard","has-post-thumbnail","hentry","category-beisbol","category-grandes-ligas","category-portada","tag-tendencia"],"_links":{"self":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2964633","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts"}],"about":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/types\/post"}],"author":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/users\/1"}],"replies":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/comments?post=2964633"}],"version-history":[{"count":2,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2964633\/revisions"}],"predecessor-version":[{"id":2964636,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/posts\/2964633\/revisions\/2964636"}],"wp:featuredmedia":[{"embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media\/2964634"}],"wp:attachment":[{"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/media?parent=2964633"}],"wp:term":[{"taxonomy":"category","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/categories?post=2964633"},{"taxonomy":"post_tag","embeddable":true,"href":"https:\/\/agpnoticias.com\/news\/wp-json\/wp\/v2\/tags?post=2964633"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}